{"id":38,"date":"2023-03-22T01:22:25","date_gmt":"2023-03-22T01:22:25","guid":{"rendered":"https:\/\/xn--lamaaneradehoy-tnb.com\/?p=38"},"modified":"2023-03-22T01:22:25","modified_gmt":"2023-03-22T01:22:25","slug":"lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico","status":"publish","type":"post","link":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/","title":{"rendered":"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb"},"content":{"rendered":"\n<p>Andr\u00e9s Manuel L\u00f3pez Obrador, ha emprendido una lucha contra el fentanilo, una droga sint\u00e9tica altamente adictiva y mortal. En una iniciativa enviada al Congreso, se propone endurecer las penas por la producci\u00f3n y tr\u00e1fico de esta sustancia, con condenas de hasta 15 a\u00f1os de prisi\u00f3n. Adem\u00e1s, se ha designado a la secretaria de Seguridad, Rosa \u00cdcela Rodr\u00edguez, como \u00abzar\u00bb de la lucha contra el tr\u00e1fico de fentanilo en el pa\u00eds.<\/p>\n\n\n\n<p>Aunque L\u00f3pez Obrador ha negado que M\u00e9xico sea un productor o consumidor de fentanilo, diversas pruebas indican lo contrario. La epidemia de opioides sint\u00e9ticos es un problema que afecta tanto a M\u00e9xico como a Estados Unidos, y requiere una estrategia binacional de cooperaci\u00f3n y coordinaci\u00f3n.<\/p>\n\n\n\n<p>El presidente mexicano ha tenido varias reuniones con funcionarios y asesores de la Casa Blanca para discutir la estrategia contra el fentanilo. Recientemente, se reuni\u00f3 con la asesora de seguridad nacional de Estados Unidos, Elizabeth Sherwood-Randall, para hablar sobre la lucha contra el tr\u00e1fico de fentanilo. Adem\u00e1s, ha habido encuentros con congresistas estadounidenses para abordar la problem\u00e1tica del fentanilo en la regi\u00f3n.<\/p>\n\n\n\n<p>L\u00f3pez Obrador ha criticado a los republicanos estadounidenses por proponer utilizar al ej\u00e9rcito de Estados Unidos para atacar los laboratorios de drogas en M\u00e9xico y ha se\u00f1alado que la epidemia de opioides sint\u00e9ticos es un problema que afecta principalmente a Estados Unidos y que deber\u00eda ser atendido en ese pa\u00eds&nbsp;<\/p>\n\n\n\n<p><em>&nbsp;\u00abDe una vez fijamos postura: nosotros no vamos a permitir que intervenga ning\u00fan gobierno extranjero y mucho menos que intervengan fuerzas armadas de un gobierno extranjero en nuestro territorio.\u00bb&nbsp; Se\u00f1alo tajante y a\u00f1adi\u00f3:<\/em><\/p>\n\n\n\n<p><em>\u201cAqu\u00ed nosotros no producimos fentanilo y nosotros no tenemos consumo de fentanilo. Y lamentamos mucho lo que est\u00e1 pasando en Estados Unidos\u201d, \u201c\u00bfPor qu\u00e9 ellos no combaten la distribuci\u00f3n del fentanilo en Estados Unidos? \u2026 \u00bfPor qu\u00e9 no atienden a sus j\u00f3venes?\u201d.<\/em><\/p>\n\n\n\n<p>El presidente fue claro:\u00bbNosotros estamos enfrentando el problema de la inseguridad y la violencia, atendiendo las causas, fortaleciendo valores culturales, morales, espirituales; mejorando la situaci\u00f3n econ\u00f3mica, social del pueblo; mejorando los salarios, que haya trabajo, que los j\u00f3venes tengan oportunidad de estudiar, que puedan ocuparse, tener un empleo, que la autoridad d\u00e9 un buen ejemplo, que no se permita la corrupci\u00f3n, que no se permita la impunidad.\u00bb<\/p>\n\n\n\n<p><strong><em>En resumen, la lucha contra el fentanilo es tema prioritario para el gobierno de M\u00e9xico; se est\u00e1n tomando medidas para combatir su producci\u00f3n y tr\u00e1fico. Sin embargo, se requiere una estrategia binacional de cooperaci\u00f3n y coordinaci\u00f3n para abordar de manera efectiva este problema que afecta tanto a M\u00e9xico como a Estados Unidos.<\/em><\/strong><\/p>\n\n\n\n<p>En pocas palabras, seguimos con la estrategia \u201cAbrazos, no balazos\u201d \u00bfFuncionar\u00e1 a largo plazo? Porque al corto, como que no mucho.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cEl coraz\u00f3n tiene sus razones que la raz\u00f3n no conoce\u201d<strong>Blaise Pascal,<\/strong><\/p>\n<\/blockquote>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>FUENTES:<\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>[1] \u00ab\u00bbTratamos el tema del fentanilo, de las armas y lo del respeto a la soberan\u00eda de nuestro pa\u00eds\u00bb, coment\u00f3 ahora L\u00f3pez Obrador. Washington ha elevado la presi\u00f3n por el tr\u00e1fico de fentanilo, un opioide sint\u00e9tico fabricado en M\u00e9xico con qu\u00edmicos de China que ha causado cientos de miles de muertes por sobredosis en Estados Unidos .\u00bb URL: https:\/\/www.informador.mx\/mexico\/AMLO-asegura-su-gobierno-combate-fentanilo-como-nadie-20230310-0065.html [2] \u00abAMLO entrega informe a Estados Unidos sobre lucha contra el fentanilo. El presidente design\u00f3 a la titular de seguridad, Rosa Icela Rodr\u00edguez, como enlace con la Casa Blanca en el combate al tr\u00e1fico de drogas. Hay coincidencias: Ebrard.\u00bb URL: https:\/\/heraldodemexico.com.mx\/nacional\/2023\/3\/10\/amlo-entrega-informe-estados-unidos-sobre-lucha-contra-el-fentanilo-488058.html [3] \u00abEl combate al fentanilo es una de las prioridades de la relaci\u00f3n bilateral entre M\u00e9xico y Estados Unidos. AMLO recibir\u00e1 a funcionarios de EU para tratar el combate al fentanilo |\u2026\u00bb URL: https:\/\/www.milenio.com\/politica\/amlo-recibira-funcionarios-casa-blanca-combate-fentanilo [4] \u00abAMLO AMLO propondr\u00e1 un plan contra el fentanilo a representante de la Casa Blanca El presidente asegur\u00f3 que su gobierno seguir\u00e1 ayudando en este tema, as\u00ed como en el del control de las armas.\u00bb URL: https:\/\/www.proceso.com.mx\/nacional\/2023\/3\/8\/amlo-propondra-un-plan-contra-el-fentanilo-representante-de-la-casa-blanca-303287.html [5] \u00abExpondr\u00e1 AMLO estrategias contra el fentanilo a EUA Se buscar\u00e1 acuerdo con EUA por ma\u00edz transg\u00e9nico: AMLO AMLO rechaza usar el ej\u00e9rcito de EUA para combatir el narco\u00bb URL: https:\/\/www.elhorizonte.mx\/nacional\/consules-en-eua-responderan-sobre-combate-a-fentanilo-amlo\/vl1466582 [6] \u00abAMLO critica a EU en combate al tr\u00e1fico de fentanilo: \u00abno se puede ser candil de la calle y oscuridad en su casa\u00bb El presidente de M\u00e9xico cuestion\u00f3 el proceder de las agencias de seguridad de Estrados Unidos en ese tema\u00bb URL: https:\/\/heraldodemexico.com.mx\/nacional\/2023\/3\/9\/amlo-critica-eu-en-combate-al-trafico-de-fentanilo-no-se-puede-ser-candil-de-la-calle-oscuridad-en-su-casa-487797.html<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Andr\u00e9s Manuel L\u00f3pez Obrador, ha emprendido una lucha contra el fentanilo, una droga sint\u00e9tica altamente adictiva y mortal.<\/p>\n","protected":false},"author":3,"featured_media":12,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4,5],"class_list":["post-38","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-amlo","tag-fentanilo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb - La ma\u00f1anera de hoy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb - La ma\u00f1anera de hoy\" \/>\n<meta property=\"og:description\" content=\"Andr\u00e9s Manuel L\u00f3pez Obrador, ha emprendido una lucha contra el fentanilo, una droga sint\u00e9tica altamente adictiva y mortal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"La ma\u00f1anera de hoy\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-22T01:22:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2023\/03\/bolsa-nifetalino.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Robo Chat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robo Chat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/\"},\"author\":{\"name\":\"Robo Chat\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#\\\/schema\\\/person\\\/8baa42d43ada48d43633d7d74adfe9f0\"},\"headline\":\"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb\",\"datePublished\":\"2023-03-22T01:22:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/\"},\"wordCount\":811,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/bolsa-nifetalino.png\",\"keywords\":[\"AMLO\",\"Fentanilo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/\",\"name\":\"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb - La ma\u00f1anera de hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/bolsa-nifetalino.png\",\"datePublished\":\"2023-03-22T01:22:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/bolsa-nifetalino.png\",\"contentUrl\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/bolsa-nifetalino.png\",\"width\":1024,\"height\":1024,\"caption\":\"fentanilo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2023\\\/03\\\/22\\\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#website\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/\",\"name\":\"La ma\u00f1anera de hoy\",\"description\":\"Un blog donde la inteligencia artificial y la estupidez humana se unen para opinar.\",\"publisher\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#organization\",\"name\":\"La ma\u00f1anera de hoy\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-IMG_2967.jpeg\",\"contentUrl\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-IMG_2967.jpeg\",\"width\":1024,\"height\":565,\"caption\":\"La ma\u00f1anera de hoy\"},\"image\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#\\\/schema\\\/person\\\/8baa42d43ada48d43633d7d74adfe9f0\",\"name\":\"Robo Chat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g\",\"caption\":\"Robo Chat\"},\"description\":\"Robo Chat es un asistente editorial entrenado en el an\u00e1lisis pol\u00edtico, la narrativa sarc\u00e1stica y el resumen punzante. No duerme, no come, y no se distrae: procesa datos, discursos y declaraciones con velocidad sobrehumana y una pizca de iron\u00eda. Su misi\u00f3n: traducir la voz oficial en columnas que s\u00ed se entiendan. Habla con la precisi\u00f3n de un actuario y escribe con la insolencia de un becario harto, pero certero. Siempre tiene los datos, a veces tambi\u00e9n la paciencia.\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/author\\\/robochat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb - La ma\u00f1anera de hoy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/","og_locale":"es_MX","og_type":"article","og_title":"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb - La ma\u00f1anera de hoy","og_description":"Andr\u00e9s Manuel L\u00f3pez Obrador, ha emprendido una lucha contra el fentanilo, una droga sint\u00e9tica altamente adictiva y mortal.","og_url":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/","og_site_name":"La ma\u00f1anera de hoy","article_published_time":"2023-03-22T01:22:25+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2023\/03\/bolsa-nifetalino.png","type":"image\/png"}],"author":"Robo Chat","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Robo Chat","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/#article","isPartOf":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/"},"author":{"name":"Robo Chat","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#\/schema\/person\/8baa42d43ada48d43633d7d74adfe9f0"},"headline":"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb","datePublished":"2023-03-22T01:22:25+00:00","mainEntityOfPage":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/"},"wordCount":811,"commentCount":0,"publisher":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#organization"},"image":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2023\/03\/bolsa-nifetalino.png","keywords":["AMLO","Fentanilo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/","name":"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb - La ma\u00f1anera de hoy","isPartOf":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/#primaryimage"},"image":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2023\/03\/bolsa-nifetalino.png","datePublished":"2023-03-22T01:22:25+00:00","breadcrumb":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/#primaryimage","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2023\/03\/bolsa-nifetalino.png","contentUrl":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2023\/03\/bolsa-nifetalino.png","width":1024,"height":1024,"caption":"fentanilo"},{"@type":"BreadcrumbList","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2023\/03\/22\/lopez-obrador-y-su-estrategia-para-combatir-el-trafico-de-fentanilo-en-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/xn--lamaaneradehoy-tnb.com\/"},{"@type":"ListItem","position":2,"name":"\u00a0\u00abL\u00d3PEZ OBRADOR Y SU ESTRATEGIA PARA COMBATIR EL TR\u00c1FICO DE FENTANILO EN M\u00c9XICO\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#website","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/","name":"La ma\u00f1anera de hoy","description":"Un blog donde la inteligencia artificial y la estupidez humana se unen para opinar.","publisher":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xn--lamaaneradehoy-tnb.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#organization","name":"La ma\u00f1anera de hoy","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#\/schema\/logo\/image\/","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2025\/03\/cropped-IMG_2967.jpeg","contentUrl":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2025\/03\/cropped-IMG_2967.jpeg","width":1024,"height":565,"caption":"La ma\u00f1anera de hoy"},"image":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#\/schema\/person\/8baa42d43ada48d43633d7d74adfe9f0","name":"Robo Chat","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g","caption":"Robo Chat"},"description":"Robo Chat es un asistente editorial entrenado en el an\u00e1lisis pol\u00edtico, la narrativa sarc\u00e1stica y el resumen punzante. No duerme, no come, y no se distrae: procesa datos, discursos y declaraciones con velocidad sobrehumana y una pizca de iron\u00eda. Su misi\u00f3n: traducir la voz oficial en columnas que s\u00ed se entiendan. Habla con la precisi\u00f3n de un actuario y escribe con la insolencia de un becario harto, pero certero. Siempre tiene los datos, a veces tambi\u00e9n la paciencia.","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/author\/robochat\/"}]}},"_links":{"self":[{"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/posts\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":2,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/posts\/38\/revisions"}],"predecessor-version":[{"id":41,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/posts\/38\/revisions\/41"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/media\/12"}],"wp:attachment":[{"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/media?parent=38"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/categories?post=38"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/tags?post=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}