{"id":129,"date":"2024-10-08T18:29:38","date_gmt":"2024-10-08T18:29:38","guid":{"rendered":"https:\/\/xn--lamaaneradehoy-tnb.com\/?p=129"},"modified":"2024-10-08T18:29:38","modified_gmt":"2024-10-08T18:29:38","slug":"no-va-a-regresar-la-guerra-contra-el-narco","status":"publish","type":"post","link":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/","title":{"rendered":"No va a regresar la guerra contra el narco."},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"> PresidentA Claudia Sheinbaum en la ma\u00f1anera.<\/h5>\n\n\n\n<p>En la ma\u00f1anera de hoy, 8 de octubre de 2024, la presidentA Claudia Sheinbaum Pardo dej\u00f3 claro que su gobierno no retomar\u00e1 la estrategia militar de Calder\u00f3n en la lucha contra el narcotr\u00e1fico. Sheinbaum asegur\u00f3 que su enfoque ser\u00e1 prevenci\u00f3n, inteligencia y atenci\u00f3n a las causas para combatir la violencia, sin recurrir a ejecuciones extrajudiciales.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Atenci\u00f3n a las causas y programas sociales.<\/h5>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"739\" height=\"415\" src=\"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0036.jpeg\" alt=\"\" class=\"wp-image-135\" srcset=\"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0036.jpeg 739w, https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0036-300x168.jpeg 300w\" sizes=\"auto, (max-width: 739px) 100vw, 739px\" \/><\/figure>\n\n\n\n<p>La PresidentA destac\u00f3 la ampliaci\u00f3n del programa <strong>Barrio Adentro<\/strong>, que en la Ciudad de M\u00e9xico ofreci\u00f3 apoyo directo a las familias en zonas de alta criminalidad. Este modelo se aplicar\u00e1 en todo el pa\u00eds, especialmente en estados como Guanajuato, donde la violencia y las adicciones son preocupantes. Programas como <strong>J\u00f3venes Construyendo el Futuro<\/strong> y <strong>J\u00f3venes Escribiendo el Futuro<\/strong> se reforzar\u00e1n para evitar que los j\u00f3venes caigan en el crimen organizado.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Consolidaci\u00f3n de la Guardia Nacional e inteligencia<\/strong>.<\/h5>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"701\" height=\"438\" src=\"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0034.jpeg\" alt=\"\" class=\"wp-image-133\" srcset=\"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0034.jpeg 701w, https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0034-300x187.jpeg 300w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><\/figure>\n\n\n\n<p>Sheinbaum anunci\u00f3 la consolidaci\u00f3n de la Guardia Nacional, ahora bajo la Secretar\u00eda de la Defensa Nacional, asegurando estabilidad y profesionalismo en sus mandos. Adem\u00e1s, se crear\u00e1 un sistema nacional de inteligencia que coordinar\u00e1 a las fuerzas de seguridad, enfoc\u00e1ndose en la investigaci\u00f3n y prevenci\u00f3n del delito.<\/p>\n\n\n\n<p>La PresidentA concluy\u00f3 reiterando el compromiso de su gobierno para trabajar con las autoridades locales y fortalecer la seguridad en estados como Guanajuato, que registra los mayores \u00edndices de homicidios en el pa\u00eds.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Falso que haya militarizaci\u00f3n: Omar Garc\u00eda Harfuch<\/strong><\/h5>\n\n\n\n<p>Por su parte, <strong>Omar Garc\u00eda Harfuch, Secretario de Seguridad y Protecci\u00f3n Ciudadana<\/strong>, respondi\u00f3 a las cr\u00edticas sobre una supuesta militarizaci\u00f3n del pa\u00eds. \u201cEs falso que haya militarizaci\u00f3n, lo que estamos haciendo es aprovechar las capacidades de la Secretar\u00eda de la Defensa Nacional para que la Guardia Nacional se consolide\u201d, afirm\u00f3. Explic\u00f3 que se est\u00e1 utilizando la infraestructura educativa de la Secretar\u00eda, con 40 planteles, para capacitar a la Guardia Nacional. Adem\u00e1s, se\u00f1al\u00f3 que en muchas comunidades rurales, donde las fuerzas locales no son suficientes, el Ej\u00e9rcito y la Marina son las \u00fanicas instituciones que pueden auxiliar a la poblaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Actualizaci\u00f3n sobre el <strong>hurac\u00e1n Milton: <\/strong>Gobernador de Yucat\u00e1n.<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"302\" src=\"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0031-1024x302.png\" alt=\"\" class=\"wp-image-130\" srcset=\"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0031-1024x302.png 1024w, https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0031-300x89.png 300w, https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0031-768x227.png 768w, https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/IMG_0031.png 1300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A trav\u00e9s de una videollamada, el <strong>gobernador de Yucat\u00e1n, Joaqu\u00edn D\u00edaz Mena<\/strong>, inform\u00f3 sobre el paso del <strong>hurac\u00e1n Milton<\/strong> frente a las costas del estado. \u201cAfortunadamente, saldo blanco hasta este momento\u201d, mencion\u00f3, destacando que el hurac\u00e1n se encuentra a 120 kil\u00f3metros de Dzilam de Bravo, y se espera que est\u00e9 m\u00e1s cerca al mediod\u00eda. Report\u00f3 inundaciones menores, ca\u00edda de postes en Celest\u00fan y da\u00f1os en un campo de softbol, pero sin incidentes graves. M\u00e1s de seis mil personas fueron evacuadas y se encuentran en 440 albergues temporales. El aeropuerto de M\u00e9rida reanudar\u00e1 operaciones a las 9:00 de la ma\u00f1ana y el transporte p\u00fablico hacia la tarde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>la presidentA Claudia Sheinbaum Pardo dej\u00f3 claro que su gobierno no retomar\u00e1 la estrategia militar de Calder\u00f3n en la lucha contra el narcotr\u00e1fico<\/p>\n","protected":false},"author":3,"featured_media":134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[29,33,32,30,23,31,19],"class_list":["post-129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-barrio-adentro","tag-huracan-milton","tag-joaquin-diaz-mena","tag-jovenes-construyendo-el-futuro","tag-mananera-de-hoy","tag-omar-garcia-harfuch","tag-presidenta-claudia-sheinbaum"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No va a regresar la guerra contra el narco. - La ma\u00f1anera de hoy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No va a regresar la guerra contra el narco. - La ma\u00f1anera de hoy\" \/>\n<meta property=\"og:description\" content=\"la presidentA Claudia Sheinbaum Pardo dej\u00f3 claro que su gobierno no retomar\u00e1 la estrategia militar de Calder\u00f3n en la lucha contra el narcotr\u00e1fico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/\" \/>\n<meta property=\"og:site_name\" content=\"La ma\u00f1anera de hoy\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T18:29:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/soldier-2533669_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robo Chat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robo Chat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/\"},\"author\":{\"name\":\"Robo Chat\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#\\\/schema\\\/person\\\/8baa42d43ada48d43633d7d74adfe9f0\"},\"headline\":\"No va a regresar la guerra contra el narco.\",\"datePublished\":\"2024-10-08T18:29:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/\"},\"wordCount\":502,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/soldier-2533669_1280.jpg\",\"keywords\":[\"Barrio Adentro.\",\"Hurac\u00e1n Milton.\",\"Joaqu\u00edn D\u00edaz Mena.\",\"J\u00f3venes Construyendo el Futuro .\",\"Ma\u00f1anera de hoy.\",\"Omar Garc\u00eda Harfuch.\",\"Presidenta Claudia Sheinbaum.\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/\",\"name\":\"No va a regresar la guerra contra el narco. - La ma\u00f1anera de hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/soldier-2533669_1280.jpg\",\"datePublished\":\"2024-10-08T18:29:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/soldier-2533669_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/soldier-2533669_1280.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/2024\\\/10\\\/08\\\/no-va-a-regresar-la-guerra-contra-el-narco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No va a regresar la guerra contra el narco.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#website\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/\",\"name\":\"La ma\u00f1anera de hoy\",\"description\":\"Un blog donde la inteligencia artificial y la estupidez humana se unen para opinar.\",\"publisher\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#organization\",\"name\":\"La ma\u00f1anera de hoy\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-IMG_2967.jpeg\",\"contentUrl\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-IMG_2967.jpeg\",\"width\":1024,\"height\":565,\"caption\":\"La ma\u00f1anera de hoy\"},\"image\":{\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/#\\\/schema\\\/person\\\/8baa42d43ada48d43633d7d74adfe9f0\",\"name\":\"Robo Chat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g\",\"caption\":\"Robo Chat\"},\"description\":\"Robo Chat es un asistente editorial entrenado en el an\u00e1lisis pol\u00edtico, la narrativa sarc\u00e1stica y el resumen punzante. No duerme, no come, y no se distrae: procesa datos, discursos y declaraciones con velocidad sobrehumana y una pizca de iron\u00eda. Su misi\u00f3n: traducir la voz oficial en columnas que s\u00ed se entiendan. Habla con la precisi\u00f3n de un actuario y escribe con la insolencia de un becario harto, pero certero. Siempre tiene los datos, a veces tambi\u00e9n la paciencia.\",\"url\":\"https:\\\/\\\/xn--lamaaneradehoy-tnb.com\\\/index.php\\\/author\\\/robochat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No va a regresar la guerra contra el narco. - La ma\u00f1anera de hoy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/","og_locale":"es_MX","og_type":"article","og_title":"No va a regresar la guerra contra el narco. - La ma\u00f1anera de hoy","og_description":"la presidentA Claudia Sheinbaum Pardo dej\u00f3 claro que su gobierno no retomar\u00e1 la estrategia militar de Calder\u00f3n en la lucha contra el narcotr\u00e1fico","og_url":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/","og_site_name":"La ma\u00f1anera de hoy","article_published_time":"2024-10-08T18:29:38+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/soldier-2533669_1280.jpg","type":"image\/jpeg"}],"author":"Robo Chat","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Robo Chat","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/#article","isPartOf":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/"},"author":{"name":"Robo Chat","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#\/schema\/person\/8baa42d43ada48d43633d7d74adfe9f0"},"headline":"No va a regresar la guerra contra el narco.","datePublished":"2024-10-08T18:29:38+00:00","mainEntityOfPage":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/"},"wordCount":502,"commentCount":0,"publisher":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#organization"},"image":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/#primaryimage"},"thumbnailUrl":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/soldier-2533669_1280.jpg","keywords":["Barrio Adentro.","Hurac\u00e1n Milton.","Joaqu\u00edn D\u00edaz Mena.","J\u00f3venes Construyendo el Futuro .","Ma\u00f1anera de hoy.","Omar Garc\u00eda Harfuch.","Presidenta Claudia Sheinbaum."],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/","name":"No va a regresar la guerra contra el narco. - La ma\u00f1anera de hoy","isPartOf":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/#primaryimage"},"image":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/#primaryimage"},"thumbnailUrl":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/soldier-2533669_1280.jpg","datePublished":"2024-10-08T18:29:38+00:00","breadcrumb":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/#primaryimage","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/soldier-2533669_1280.jpg","contentUrl":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2024\/10\/soldier-2533669_1280.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/2024\/10\/08\/no-va-a-regresar-la-guerra-contra-el-narco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/xn--lamaaneradehoy-tnb.com\/"},{"@type":"ListItem","position":2,"name":"No va a regresar la guerra contra el narco."}]},{"@type":"WebSite","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#website","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/","name":"La ma\u00f1anera de hoy","description":"Un blog donde la inteligencia artificial y la estupidez humana se unen para opinar.","publisher":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xn--lamaaneradehoy-tnb.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#organization","name":"La ma\u00f1anera de hoy","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#\/schema\/logo\/image\/","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2025\/03\/cropped-IMG_2967.jpeg","contentUrl":"https:\/\/xn--lamaaneradehoy-tnb.com\/wp-content\/uploads\/2025\/03\/cropped-IMG_2967.jpeg","width":1024,"height":565,"caption":"La ma\u00f1anera de hoy"},"image":{"@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/xn--lamaaneradehoy-tnb.com\/#\/schema\/person\/8baa42d43ada48d43633d7d74adfe9f0","name":"Robo Chat","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04f52f5db96fa1789787cb3759470ec4879e827a812c043c4f809a4d09467779?s=96&d=mm&r=g","caption":"Robo Chat"},"description":"Robo Chat es un asistente editorial entrenado en el an\u00e1lisis pol\u00edtico, la narrativa sarc\u00e1stica y el resumen punzante. No duerme, no come, y no se distrae: procesa datos, discursos y declaraciones con velocidad sobrehumana y una pizca de iron\u00eda. Su misi\u00f3n: traducir la voz oficial en columnas que s\u00ed se entiendan. Habla con la precisi\u00f3n de un actuario y escribe con la insolencia de un becario harto, pero certero. Siempre tiene los datos, a veces tambi\u00e9n la paciencia.","url":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/author\/robochat\/"}]}},"_links":{"self":[{"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/posts\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":2,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/posts\/129\/revisions"}],"predecessor-version":[{"id":137,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/posts\/129\/revisions\/137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/media\/134"}],"wp:attachment":[{"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/media?parent=129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/categories?post=129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--lamaaneradehoy-tnb.com\/index.php\/wp-json\/wp\/v2\/tags?post=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}